{"id":24275,"date":"2022-09-29T16:09:30","date_gmt":"2022-09-29T21:09:30","guid":{"rendered":"https:\/\/comfanorte.com.co\/index\/?page_id=24275"},"modified":"2022-09-29T16:19:41","modified_gmt":"2022-09-29T21:19:41","slug":"glosario","status":"publish","type":"page","link":"https:\/\/comfanorte.com.co\/index\/glosario\/","title":{"rendered":"Glosario"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"24275\" class=\"elementor elementor-24275\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff6b86f e-flex e-con-boxed e-con\" data-id=\"ff6b86f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e8d613 elementor-widget elementor-widget-spacer\" data-id=\"8e8d613\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af5d54d elementor-widget elementor-widget-heading\" data-id=\"af5d54d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Glosario<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3f939c elementor-widget elementor-widget-text-editor\" data-id=\"d3f939c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.14.0 - 26-06-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>CAJAS<b> DE COMPENSACI\u00d3N: <\/b>son personas jur\u00eddicas de derecho privado sin \u00e1nimo de lucro, organizadas como corporaciones, de naturaleza especial\u00edsima que desarrollan una funci\u00f3n social al recaudar, operar y gestionar los aportes parafiscales del subsidio familiar para que beneficien a los trabajadores y sus familias. Se encuentran sometidos a la inspecci\u00f3n, control y vigilancia del Estado en tanto ejercen funciones p\u00fablicas y cumplen con obligaciones dentro del Sistema General de Seguridad Social.<\/p><p><b>EMPLEADORES AFILIADOS:<\/b> Son afiliados a una Caja de Compensaci\u00f3n Familiar los empleadores que por cumplir los requisitos establecidos y los respectivos estatutos de la Corporaci\u00f3n, hayan sido admitidos por su Consejo Directivo o por su Director Administrativo, cuando le haya sido delegada tal facultad. La calidad, derechos y obligaciones de miembro o afiliado se adquieren a partir de la fecha de comunicaci\u00f3n de su admisi\u00f3n y su car\u00e1cter es personal e intransferible. Los estatutos de las Cajas de Compensaci\u00f3n se\u00f1alar\u00e1n los derechos y las obligaciones de sus miembros o afiliados.<\/p><p><b>IPC:<\/b> \u00cdndice de Precios al Consumidor. Es una medida del cambio (variaci\u00f3n), en el precio de bienes y servicios representativos del consumo de los hogares del pa\u00eds conocido como canasta. La variaci\u00f3n, entre un periodo de tiempo y otro, la calcula el Departamento Administrativo Nacional de Estad\u00edstica (DANE).<\/p><p><b>SISTEMA DE SUBSIDIO FAMILIAR:<\/b> es el conjunto de instituciones pol\u00edticas y normativas orientadas a la protecci\u00f3n integral del trabajador y su familia, asegurando los fines de la prestaci\u00f3n social subsidio familiar. El sistema funciona como un di\u00e1logo entre el Estado, que dictamina la pol\u00edtica social y ejerce el control y vigilancia sobre las corporaciones recaudadoras y pagadoras de los recursos del subsidio familiar; los empleadores, que afilian a sus trabajadores y pagan los aportes; las Cajas de Compensaci\u00f3n Familiar que recaudan, operan y gestionan los aportes, y pagan la prestaci\u00f3n a los trabajadores beneficiarios en dinero, especie y servicios; y el trabajador y su familia, quienes reciben los beneficios.<\/p><p>Es el deber de todos los miembros del Sistema del Subsidio Familiar propender por el cumplimiento de los fines del Sistema en todas sus actuaciones.<\/p><p><b>SUBSIDIO EN DINERO:<\/b> Es la cuota monetaria que se paga por cada persona a cargo que de derecho a la prestaci\u00f3n.<\/p><p><b>SUBSIDIO FAMILIAR:<\/b> prestaci\u00f3n social pagadera en dinero, especie y servicios a los trabajadores de medianos y menores ingresos, en proporci\u00f3n al n\u00famero de personas a cargo, y su objetivo fundamental consiste en el alivio de las cargas econ\u00f3micas que representa el sostenimiento de la familia, como n\u00facleo b\u00e1sico de la sociedad. El derecho al subsidio familiar es irrenunciable.<\/p><p><b>SUBSIDIO EN ESPECIE:<\/b> Es el reconocido en alimentos, vestidos, becas de estudio, textos escolares, drogas y dem\u00e1s frutos o g\u00e9neros diferentes al dinero.<\/p><p><b>SUBSIDIO EN SERVICIOS:<\/b> Es aquel que se reconoce a trav\u00e9s de la utilizaci\u00f3n de las obras y programas sociales que organicen las Cajas de Compensaci\u00f3n Familiar dentro del orden de prioridades prescrito en la ley.<\/p><p><b>TRABAJADORES AFILIADOS:<\/b> Se entienden afiliados al Sistema del Subsidio Familiar, los trabajadores de car\u00e1cter permanente al servicio de los empleadores previstos en el art\u00edculo 7\u00b0 de la Ley 21 de 1982, en cuanto el respectivo empleador haya sido aceptado y permanezca vigente su vinculaci\u00f3n por no haber sido objeto de retiro voluntario debidamente aceptado, expulsi\u00f3n o suspensi\u00f3n de conformidad con lo previsto en el art\u00edculo 45 de la citada Ley 21.<\/p><p>La afiliaci\u00f3n de los pensionados o trabajadores independientes permanece vigente desde su aceptaci\u00f3n hasta su retiro voluntario, suspensi\u00f3n o p\u00e9rdida de su calidad por el no pago de los aportes. Son trabajadores afiliados al Sistema del Subsidio Familiar:<\/p><p><b>\u2022 Trabajador dependiente: <\/b>Es aquel que se encuentra vinculado mediante un contrato de trabajo. Este tipo de trabajador debe cumplir una jornada laboral, a la vez que se encuentra sujeto a la subordinaci\u00f3n de su empleador para el desempe\u00f1o de sus labores y recibe una remuneraci\u00f3n denominada salario. Es requisito que el empleador cuente con la afiliaci\u00f3n vigente a la Caja de\u00a0<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1em; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">Compensaci\u00f3n Familiar.<\/span><\/p><p>\u2022<b> Trabajador independiente:<\/b> Es aquella persona que no est\u00e1 vinculada a una empresa mediante un contrato de trabajo, sino mediante un contrato por prestaci\u00f3n de servicios, y recibe como contraprestaci\u00f3n el pago de honorarios y\/o comisiones, o que trabajan por cuenta propia. Su vinculaci\u00f3n a la Caja de Compensaci\u00f3n Familiar es voluntaria.<\/p><p><b>\u2022 Facultativo: <\/b>Son las personas que, no encontr\u00e1ndose dentro de las categor\u00edas anteriores y no requieren vinculaci\u00f3n obligatoria, pueden tener acceso a los servicios sociales de las Cajas de Compensaci\u00f3n Familiar por disposici\u00f3n de la ley o en desarrollo de convenios celebrados.<\/p><p><b>Pensionado: <\/b>Persona a quien se le ha reconocido una prestaci\u00f3n econ\u00f3mica por vejez, esto es que ha cumplido con los requisitos esenciales y concurrentes de edad, semanas cotizadas o tiempo de servicios se\u00f1alado por la ley para gozar de una prestaci\u00f3n de vejez o de jubilaci\u00f3n, y le haya sido reconocida una asignaci\u00f3n de retiro o pensi\u00f3n, seg\u00fan el caso; por invalidez, con la acreditaci\u00f3n de los requisitos establecidos; y\/o por sustituci\u00f3n pensional o sobrevivientes. Su vinculaci\u00f3n a la Caja de Compensaci\u00f3n Familiar es voluntaria.<\/p><p><b>DEFINICIONES REFERENTES A LAS AFILIACIONES\u00a0<\/b>Las definiciones a continuaci\u00f3n se tendr\u00e1n en cuenta de forma especial en lo referente a los afiliados y las afiliaciones del Sistema de Subsidio Familiar.<\/p><p><b>ACREDITACI\u00d3N DE LA DISCAPACIDAD:<\/b> Presentaci\u00f3n de la certificaci\u00f3n de discapacidad, que es un documento oficial, personal e intransferible que se entrega despu\u00e9s de la valoraci\u00f3n cl\u00ednica multidisciplinaria y acredita la condici\u00f3n legal de persona con discapacidad, de acuerdo con las directrices expedidas por el Ministerio de Salud y Protecci\u00f3n Social o la entidad que haga sus veces. La acreditaci\u00f3n puede ser expedida por las IPS\u2019s autorizadas por las Secretar\u00edas de Salud o las entidades que hagan sus veces, las Juntas Regionales de Calificaci\u00f3n y\/o las Administradoras de Riesgos Laborales, o cualquier otro que para ello autorice el Ministerio de Salud y Protecci\u00f3n Social de acuerdo con la reglamentaci\u00f3n que para ello emita.<\/p><p><b>ACREDITACI\u00d3N DE ESCOLARIDAD O DE ESTUDIOS:<\/b> Documento a trav\u00e9s del cual se certifica o comprueba que los menores de edad se encuentran cursando un programa acad\u00e9mico en una instituci\u00f3n autorizada por el Estado.<\/p><p><b>ADOPCI\u00d3N:<\/b> Es el acto jur\u00eddico, mediante el cual se crea un v\u00ednculo de parentesco entre una o dos personas y queda consignado en el Registro Civil de nacimiento del adoptado.<\/p><p><b>COBERTURA:<\/b> Es el tiempo durante el cual un afiliado puede acceder a los servicios de la Caja de Compensaci\u00f3n Familiar. El empleador se entiende afiliado a partir del momento en que se acepta su afiliaci\u00f3n. El trabajador se entiende afiliado desde el momento en que se le comunica su aceptaci\u00f3n al empleador y hasta el momento en que este se desafilia.<\/p><p>La calidad de beneficiario y de persona a cargo debe probarse ante la Caja, y se entender\u00e1n vinculadas \u00fanicamente a partir del momento en que sean registrados en el sistema de informaci\u00f3n de la Caja, luego de que esta haya realizado la respectiva verificaci\u00f3n de la informaci\u00f3n y de los documentos probatorios.<\/p><p><b>CUSTODIA:<\/b> Es el oficio o funci\u00f3n mediante el cual se tiene poder para criar, educar, orientar, conducir, formar h\u00e1bitos, dirigir y disciplinar la conducta, siempre con la mira puesta en el ni\u00f1o, ni\u00f1a y\/o adolescente, en el educando, en el incapaz de obrar y auto regular en forma independiente su comportamiento.<\/p><p>La custodia debe ser expedida por la correspondiente autoridad competente, ya sea ICBF, notarios, centros de conciliaci\u00f3n debidamente autorizados, defensor\u00eda del pueblo, personer\u00eda, jueces de paz, juzgado de familia, juez civil o promiscuo municipal y, en ausencia de estos, el inspector de polic\u00eda.<br \/><br \/><\/p><p><b>DEPENDIENTE POR CUSTODIA: <\/b>Es el beneficiario menor de 18 a\u00f1os, o mayores de 18 a\u00f1os en condici\u00f3n de discapacidad, que es entregado al afiliado para su cuidado y sostenimiento econ\u00f3mico. La entrega puede ser provisional o permanente y debe constar en documento emitido por autoridad competente, en los t\u00e9rminos de la presente Circular. Si el trabajador cumple con los requisitos establecidos en la norma, podr\u00e1 ser acreedor del derecho a subsidio familiar en dinero &#8211; cuota monetaria.<\/p><p><b>FORMULARIO DE AFILIACI\u00d3N:<\/b> Documento o comunicaci\u00f3n, ya sea f\u00edsico o digital, dise\u00f1ado por la Caja de Compensaci\u00f3n Familiar, con el prop\u00f3sito de que los empleadores, los pensionados, los independientes, los facultativos y el trabajador dependiente registren sus datos y los de sus beneficiarios. Este documento hace las veces de carta de solicitud de afiliaci\u00f3n.<\/p><p><b>HIJO ADOPTIVO:<\/b> Hijo que adquiere dicha condici\u00f3n cuando se efect\u00faa el proceso de adopci\u00f3n. Los hijos adoptivos tendr\u00e1n derecho a ser incluidos en la cobertura familiar desde que se adquier\u00a0dicha condici\u00f3n, en el momento mismo de su entrega a los padres adoptantes por parte del Instituto Colombiano de Bienestar Familiar o de alguna de las casas de adopci\u00f3n debidamente reconocidas por dicho Instituto.<\/p><p><b>HIJASTRO:<\/b> Hijo o hija llevados al matrimonio por uno de los c\u00f3nyuges, respecto del otro, o llevado por uno de los miembros de la uni\u00f3n marital de hecho, y sobre quien recae la custodia.<\/p><p><b>INEXACTITUD:<\/b> Evento en el que se presenta un menor valor declarado y pagado en la autoliquidaci\u00f3n de aportes frente a los aportes que efectivamente el aportante estaba obligado a declarar y pagar, seg\u00fan lo ordenado por la ley.<\/p><p><b>INSCRIPCI\u00d3N DEL GRUPO FAMILIAR:<\/b> Los afiliados deber\u00e1n inscribir ante la Caja de Compensaci\u00f3n Familiar a cada uno de los miembros que conforman su grupo familiar, anexando los documentos exigidos para cada uno de los casos, dicho formulario deber\u00e1 ser suscrito por el afiliado y el empleador cuando se trate de contrato de trabajo. En caso de realizarse la afiliaci\u00f3n por medio de sistemas de afiliaci\u00f3n virtual, la suscripci\u00f3n seguir\u00e1 las reglas sobre el particular.<\/p><p>I<b>NSCRIPCI\u00d3N INDIVIDUAL:<\/b> Es la forma de afiliaci\u00f3n que cubre a una sola persona.<\/p><p><b>MORA:<\/b> Es el incumplimiento que se genera cuando existiendo afiliaci\u00f3n no se genera la autoliquidaci\u00f3n acompa\u00f1ada del respectivo pago de las Contribuciones Parafiscales de la Protecci\u00f3n Social en los plazos establecidos en las disposiciones legales vigentes.<\/p><p><b>OMISI\u00d3N EN LA AFILIACI\u00d3N:<\/b> Es el incumplimiento de la obligaci\u00f3n de afiliar o afiliarse a alguno o algunos de los subsistemas que integran el Sistema de la Protecci\u00f3n Social y como consecuencia de ello, no haber declarado ni pagado las respectivas contribuciones parafiscales, cuando surja la obligaci\u00f3n conforme con las disposiciones legales vigentes.<\/p><p><b>OMISI\u00d3N EN LA VINCULACI\u00d3N:<\/b> Es el no reporte de la novedad de ingreso a una administradora del Sistema de la Protecci\u00f3n Social cuando surja la obligaci\u00f3n conforme con las disposiciones legales vigentes y como consecuencia de ello no se efect\u00faa el pago de los aportes a su cargo o alguno o algunos de los subsistemas que integran el Sistema de la Protecci\u00f3n Social.<\/p><p><b>PERSONA A CARGO:<\/b> Persona que integra el grupo familiar del afiliado, que depende econ\u00f3micamente de \u00e9l y que genera el reconocimiento del subsidio familiar. Est\u00e1s personas est\u00e1n determinadas dentro de las siguientes categor\u00edas: Los hijos que no sobrepasen la edad de 18 a\u00f1os, leg\u00edtimos, naturales, adoptivos y los hijastros.<br \/>Despu\u00e9s de los 12 a\u00f1os se debe acreditar la escolaridad en establecimiento docente debidamente<br \/>aprobado.<br \/>1. Los hermanos que no sobrepasen la edad de 18 a\u00f1os, hu\u00e9rfanos de padres, que convivan y<br \/>dependan econ\u00f3micamente del trabajador y que acrediten la escolaridad.<br \/>2. Los padres del trabajador beneficiario mayores de 60 a\u00f1os, siempre y cuando ninguno de los<br \/>dos reciba salario, renta o pensi\u00f3n alguna.<br \/>3. Los hijos y hermanos hu\u00e9rfanos de padres mayores de 18 a\u00f1os, los padres del afiliado<br \/>menores de 60 a\u00f1os que presenten una condici\u00f3n de discapacidad.<br \/>Los dependientes por custodia en los t\u00e9rminos establecidos por la autoridad competente.<\/p><p><b>RECONOCIMIENTO DE LA CUOTA MONETARIA:<\/b> Es la entrega del subsidio monetario mensual por parte de la Caja de Compensaci\u00f3n Familiar al afiliado con derecho a ello. Se dar\u00e1 siempre y cuando el trabajador cumpla i) mes a mes con las condiciones de ingresos, horas laboradas y personas a cargo, ii) acredite el derecho ante la Caja de Compensaci\u00f3n Familiar con la entrega de los documentos exigidos, seg\u00fan el caso y, iii) el empleador se encuentre al d\u00eda en el pago de los aportes del correspondiente trabajador\u00a0<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); font-size: 1em;\">UNI\u00d3N MARITAL DE HECHO: Es aquella conformada por dos personas (del mismo o diferente\u00a0<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); font-size: 1em;\">genero), que, sin haber celebrado matrimonio ante rito religioso o una autoridad civil, hacen una\u00a0<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); font-size: 1em;\">comunidad de vida permanente y singular.<\/span><\/p><p><b>VINCULACI\u00d3N DEL GRUPO FAMILIAR:<\/b> Es la forma de afiliaci\u00f3n en la que el afiliado, directamente o a trav\u00e9s de sus empleadores, cumple su deber de vincular, ante la Caja de Compensaci\u00f3n Familiar, a cada uno de los miembros que conforman su grupo familiar, anexando los documentos exigidos para cada uno de los casos.<\/p><p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); font-size: 1em;\"><strong>VINCULACI\u00d3N INDIVIDUAL:<\/strong> Es la forma de afiliaci\u00f3n que cubre \u00fanicamente al afiliado que no tenga\u00a0<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); font-size: 1em;\">personas a cargo.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Glosario CAJAS DE COMPENSACI\u00d3N: son personas jur\u00eddicas de derecho privado sin \u00e1nimo de lucro, organizadas como corporaciones, de naturaleza especial\u00edsima que desarrollan una funci\u00f3n social al recaudar, operar y gestionar los aportes parafiscales del subsidio familiar para que beneficien a los trabajadores y sus familias. Se encuentran sometidos a la inspecci\u00f3n, control y vigilancia del &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/comfanorte.com.co\/index\/glosario\/\" class=\"more-link\">Sigue leyendo<span class=\"screen-reader-text\"> \u00abGlosario\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.4 (Yoast SEO v20.10) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Glosario - Comfanorte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comfanorte.com.co\/index\/glosario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glosario\" \/>\n<meta property=\"og:description\" content=\"Glosario CAJAS DE COMPENSACI\u00d3N: son personas jur\u00eddicas de derecho privado sin \u00e1nimo de lucro, organizadas como corporaciones, de naturaleza especial\u00edsima que desarrollan una funci\u00f3n social al recaudar, operar y gestionar los aportes parafiscales del subsidio familiar para que beneficien a los trabajadores y sus familias. Se encuentran sometidos a la inspecci\u00f3n, control y vigilancia del &hellip; Sigue leyendo \u00abGlosario\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comfanorte.com.co\/index\/glosario\/\" \/>\n<meta property=\"og:site_name\" content=\"Comfanorte\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-29T21:19:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/comfanorte.com.co\/index\/glosario\/\",\"url\":\"https:\/\/comfanorte.com.co\/index\/glosario\/\",\"name\":\"Glosario - Comfanorte\",\"isPartOf\":{\"@id\":\"https:\/\/comfanorte.com.co\/index\/#website\"},\"datePublished\":\"2022-09-29T21:09:30+00:00\",\"dateModified\":\"2022-09-29T21:19:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/comfanorte.com.co\/index\/glosario\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/comfanorte.com.co\/index\/glosario\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/comfanorte.com.co\/index\/glosario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/comfanorte.com.co\/index\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glosario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/comfanorte.com.co\/index\/#website\",\"url\":\"https:\/\/comfanorte.com.co\/index\/\",\"name\":\"Comfanorte\",\"description\":\"Sitio oficial de la Caja de Compensaci\u00f3n Familiar de Norte de Santander\",\"publisher\":{\"@id\":\"https:\/\/comfanorte.com.co\/index\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/comfanorte.com.co\/index\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/comfanorte.com.co\/index\/#organization\",\"name\":\"Comfanorte\",\"url\":\"https:\/\/comfanorte.com.co\/index\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/comfanorte.com.co\/index\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/comfanorte.com.co\/index\/wp-content\/uploads\/2020\/05\/LogoWebsite-300x80-1.png\",\"contentUrl\":\"https:\/\/comfanorte.com.co\/index\/wp-content\/uploads\/2020\/05\/LogoWebsite-300x80-1.png\",\"width\":300,\"height\":80,\"caption\":\"Comfanorte\"},\"image\":{\"@id\":\"https:\/\/comfanorte.com.co\/index\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Glosario - Comfanorte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comfanorte.com.co\/index\/glosario\/","og_locale":"es_ES","og_type":"article","og_title":"Glosario","og_description":"Glosario CAJAS DE COMPENSACI\u00d3N: son personas jur\u00eddicas de derecho privado sin \u00e1nimo de lucro, organizadas como corporaciones, de naturaleza especial\u00edsima que desarrollan una funci\u00f3n social al recaudar, operar y gestionar los aportes parafiscales del subsidio familiar para que beneficien a los trabajadores y sus familias. Se encuentran sometidos a la inspecci\u00f3n, control y vigilancia del &hellip; Sigue leyendo \u00abGlosario\u00bb","og_url":"https:\/\/comfanorte.com.co\/index\/glosario\/","og_site_name":"Comfanorte","article_modified_time":"2022-09-29T21:19:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comfanorte.com.co\/index\/glosario\/","url":"https:\/\/comfanorte.com.co\/index\/glosario\/","name":"Glosario - Comfanorte","isPartOf":{"@id":"https:\/\/comfanorte.com.co\/index\/#website"},"datePublished":"2022-09-29T21:09:30+00:00","dateModified":"2022-09-29T21:19:41+00:00","breadcrumb":{"@id":"https:\/\/comfanorte.com.co\/index\/glosario\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comfanorte.com.co\/index\/glosario\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comfanorte.com.co\/index\/glosario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comfanorte.com.co\/index\/"},{"@type":"ListItem","position":2,"name":"Glosario"}]},{"@type":"WebSite","@id":"https:\/\/comfanorte.com.co\/index\/#website","url":"https:\/\/comfanorte.com.co\/index\/","name":"Comfanorte","description":"Sitio oficial de la Caja de Compensaci\u00f3n Familiar de Norte de Santander","publisher":{"@id":"https:\/\/comfanorte.com.co\/index\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comfanorte.com.co\/index\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/comfanorte.com.co\/index\/#organization","name":"Comfanorte","url":"https:\/\/comfanorte.com.co\/index\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/comfanorte.com.co\/index\/#\/schema\/logo\/image\/","url":"https:\/\/comfanorte.com.co\/index\/wp-content\/uploads\/2020\/05\/LogoWebsite-300x80-1.png","contentUrl":"https:\/\/comfanorte.com.co\/index\/wp-content\/uploads\/2020\/05\/LogoWebsite-300x80-1.png","width":300,"height":80,"caption":"Comfanorte"},"image":{"@id":"https:\/\/comfanorte.com.co\/index\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/comfanorte.com.co\/index\/wp-json\/wp\/v2\/pages\/24275"}],"collection":[{"href":"https:\/\/comfanorte.com.co\/index\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/comfanorte.com.co\/index\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/comfanorte.com.co\/index\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comfanorte.com.co\/index\/wp-json\/wp\/v2\/comments?post=24275"}],"version-history":[{"count":8,"href":"https:\/\/comfanorte.com.co\/index\/wp-json\/wp\/v2\/pages\/24275\/revisions"}],"predecessor-version":[{"id":24285,"href":"https:\/\/comfanorte.com.co\/index\/wp-json\/wp\/v2\/pages\/24275\/revisions\/24285"}],"wp:attachment":[{"href":"https:\/\/comfanorte.com.co\/index\/wp-json\/wp\/v2\/media?parent=24275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}